{"id":115,"date":"2016-02-06T15:07:48","date_gmt":"2016-02-06T15:07:48","guid":{"rendered":"http:\/\/www.secsanjuan.com\/inicio15\/?p=115"},"modified":"2016-02-06T15:08:31","modified_gmt":"2016-02-06T15:08:31","slug":"115","status":"publish","type":"post","link":"https:\/\/www.secsanjuan.com\/inicio15\/2016\/02\/06\/115\/","title":{"rendered":"Despidos en el Comercio"},"content":{"rendered":"<p>En conferencia de prensa ayer Ra\u00fal \u00c1vila manifest\u00f3: Hay gran cantidad de despidos en el comercio de San Juan, queremos alertar a la poblaci\u00f3n de esta situaci\u00f3n, esto est\u00e1 en erupci\u00f3n, despidos, inflaci\u00f3n, y ca\u00edda en las ventas hace que haya empleados que empiecen a estar de m\u00e1s, Despedir trabajadores es apagar un incendio con nafta. Es un hecho que el despedido consume menos, y as\u00ed no va a pasar mucho tiempo para que comercios chicos tengan que cerrar las puertas.Les vamos a pedir a los empresarios del comercio que aguantemos la situaci\u00f3n entre todos.<br \/>\nNo queremos que se repita lo que ya vivimos en el a\u00f1o&nbsp; 2001 donde de cada tres comercios uno estaba cerrado.El Sindicato va a&nbsp; salir a manifestarse. A expresar el repudio por los aumentos y los despidos.<br \/>\nEl jueves 11 de febrero sobre las 9hs nos vamos a concentrar en la sede gremial de calle Gral. Acha 65 (s) y luego marcharemos por las calles del centro de San Juan, si la situaci\u00f3n se agrava lo extenderemos a Villa Krause que tambi\u00e9n es un centro comercial grande. m\u00e1s info www.vozdelosmercantiles.com.ar<\/p>\n<br>\n\t\t\t\t<div style=\"width: 10px;\" class=\"wp-caption alignleft\" id=\"attachment_\">\n\t\t\t\t\t<a href=\"http:\/\/www.secsanjuan.com\/inicio15\/wp-content\/wpflashpageflip\/115\" target=\"_blank\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"\" height=\"\" alt=\"\" src=\"\" title=\"\" class=\"size-medium wp-image-\">\n\t\t\t\t\t\t \n\t\t\t\t\t\t\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<p class=\"wp-caption-text\"><\/p>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>En conferencia de prensa ayer Ra\u00fal \u00c1vila manifest\u00f3: Hay gran cantidad de despidos en el comercio de San Juan, queremos<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-115","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/www.secsanjuan.com\/inicio15\/wp-json\/wp\/v2\/posts\/115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.secsanjuan.com\/inicio15\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.secsanjuan.com\/inicio15\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.secsanjuan.com\/inicio15\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.secsanjuan.com\/inicio15\/wp-json\/wp\/v2\/comments?post=115"}],"version-history":[{"count":2,"href":"https:\/\/www.secsanjuan.com\/inicio15\/wp-json\/wp\/v2\/posts\/115\/revisions"}],"predecessor-version":[{"id":117,"href":"https:\/\/www.secsanjuan.com\/inicio15\/wp-json\/wp\/v2\/posts\/115\/revisions\/117"}],"wp:attachment":[{"href":"https:\/\/www.secsanjuan.com\/inicio15\/wp-json\/wp\/v2\/media?parent=115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.secsanjuan.com\/inicio15\/wp-json\/wp\/v2\/categories?post=115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.secsanjuan.com\/inicio15\/wp-json\/wp\/v2\/tags?post=115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}